{"id":1020,"count":1,"description":"","link":"https:\/\/www.dide.org\/en\/tag\/goals\/","name":"goals","slug":"goals","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.dide.org\/en\/wp-json\/wp\/v2\/tags\/1020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dide.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.dide.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.dide.org\/en\/wp-json\/wp\/v2\/posts?tags=1020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}